{"id":3284,"date":"2016-07-22T14:32:36","date_gmt":"2016-07-22T12:32:36","guid":{"rendered":"http:\/\/blog.waynabox.fr\/?p=177"},"modified":"2019-02-11T10:40:14","modified_gmt":"2019-02-11T10:40:14","slug":"top-10-plus-rooftops-europe","status":"publish","type":"post","link":"https:\/\/waynabox.com\/blog\/fr\/2016\/07\/22\/top-10-plus-rooftops-europe\/","title":{"rendered":"Top 5 des plus beaux rooftops d&#8217;Europe"},"content":{"rendered":"<p>L&#8217;\u00e9t\u00e9 est enfin l\u00e0 ! Il est donc temps de profiter des longues soir\u00e9es estivales et des derniers rayons de soleil entre amis autour d&#8217;un petit verre. Et pour cela, on s&#8217;offre m\u00eame le luxe de s&#8217;offrir un panorama magnifique sur les plus belles villes d&#8217;Europe. D\u00e9couvrez nos meilleures adresses des plus beaux rooftops.<\/p>\n<ol>\n<li><b><b>Lisbonne : le Sky Bar du Tivoli Lisboa<\/b><\/b><\/li>\n<\/ol>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-251\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/07\/sky-bar-720x450.jpg\" alt=\"sky-bar\" width=\"800\" height=\"526\" \/><\/p>\n<p>Situ\u00e9 au 9\u00e8me \u00e9tage du Tivoli Lisboa, ce rooftop est l&#8217;endroit id\u00e9al pour profiter des fins de journ\u00e9es et d\u00e9buts de soir\u00e9es autour d&#8217;un verre avec son compagnon ou ses amis. Avec le ch\u00e2teau St. Jorge \u00e0 gauche, la rivi\u00e8re Tagus en arri\u00e8re-plan et la vue panoramique sur Lisbonne devant vous, nous vous assurons que cet h\u00f4tel vaut le d\u00e9tour.<\/p>\n<p>Vous pouvez vous relaxer autour des meilleurs cocktails de la ville avec des vues \u00e0 couper le souffle. Un DJ sera pr\u00e9sent tout l&#8217;\u00e9t\u00e9 pour vous faire danser, du Mardi au Samedi jusqu&#8217;\u00e0 23h. Mais la f\u00eate ne s&#8217;arr\u00eate pas l\u00e0, une fois le ventre rempli gr\u00e2ce \u00e0 une large et divine s\u00e9lection de snacks (churros accompagn\u00e9 de sauce BBQ par exemple), vous pouvez rester jusqu&#8217;\u00e0 1h du matin pour passer du bon temps et surtout profiter de la vue.<\/p>\n<p><b style=\"line-height: 1.5;\">2. Londres : ME hotel<\/b><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-250\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/07\/ME-London-rooftop-720x398.jpg\" alt=\"ME London rooftop\" width=\"800\" height=\"381\" \/><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019hotel Melia est situ\u00e9 au coeur de Londres, son rooftop est au 10\u00e8me \u00e9tage ce qui permet d\u2019avoir une vue panoramique sur Tower Bridge, London Eye et tous les lieux touristiques. Avec leur concept \u201ctapas con vista\u201d, vous pourrez vous relaxer \u00e0 l\u2019espagnol autour d&#8217;un des meilleurs cocktails de la ville. Cet hotel est c\u00e9l\u00e8bre pour son rooftop futuriste.\u00a0<\/span><\/p>\n<p><strong>3.\u00a0<\/strong><b style=\"line-height: 1.5;\">Berlin: le Klunkerkranich<\/b><\/p>\n<figure id=\"attachment_263\" aria-describedby=\"caption-attachment-263\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-263\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/07\/Klunkerkranich-Aussicht-Abends-Juli-_3-web-720x450.jpg\" alt=\"Klunkerkranich Aussicht Abends Juli _3-web\" width=\"800\" height=\"533\" \/><figcaption id=\"caption-attachment-263\" class=\"wp-caption-text\">Credits: Julian Nelken<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">En \u00e9t\u00e9, les parcs de Berlin sont tr\u00e8s quot\u00e9s, mais comme partout les rooftops font leur apparition et le plus agr\u00e9able n\u2019est pas celui d\u2019un hotel ! Mais celui d\u2019un centre commercial. En haut vous trouverez du monde, mais pas n\u2019importe qui, l\u2019ambiance y est particuli\u00e8rement agr\u00e9able avec une musique qui ravira vos oreilles. C\u2019est un must \u00e0 faire, cette vue est consid\u00e9r\u00e9e comme \u00e9tant une des plus belles de Berlin. L&#8217;\u00e9t\u00e9 il y a des \u00e9v\u00e8nements d&#8217;organis\u00e9s, comme les cin\u00e9mas en plein air.\u00a0<\/span><\/p>\n<p><strong>4. Madrid: ME Madrid<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-248\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/07\/THE-ROOF-720x450.jpg\" alt=\"THE ROOF\" width=\"800\" height=\"549\" \/><\/p>\n<p>Du haut de l&#8217;h\u00f4tel Melia, de Madrid cette fois, vous pouvez en plus de la vue incroyable, profiter de saveurs\u00a0de diff\u00e9rents pays et de super cocktails. La vue panoramique est \u00e0 couper le souffle et nous vous conseillons d&#8217;y passer en d\u00e9but de soir\u00e9e afin de voir le coucher de soleil sur la ville.<\/p>\n<p><strong>5. Barcelone: Terraza del Claris<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-249\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/07\/claris-720x450.jpg\" alt=\"claris\" width=\"800\" height=\"548\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/07\/claris-300x205.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/07\/claris-1030x705.jpg 1030w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/07\/claris-768x526.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/07\/claris.jpg 1050w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>La Terrasse de l&#8217;h\u00f4tel Claris est un must \u00e0 Barcelone. Chaque d\u00e9but d&#8217;\u00e9t\u00e9 et depuis 24 ans, l&#8217;h\u00f4tel organise une f\u00eate rassemblant pr\u00e8s de 700 invit\u00e9s afin d&#8217;inaugurer l&#8217;ouverture de son\u00a0rooftop. Vous pouvez profiter entre amis ou en couple l&#8217;ambiance agr\u00e9able de cet h\u00f4tel qui poss\u00e8de une vue unique de la ville. Le restaurant a aussi un petit plus car le chef, Victor Ibanez, est reconnu et propose une carte vari\u00e9e pour tout type de go\u00fbt. Le coucher de soleil est superbe, vous pouvez venir go\u00fbter les cocktails accompagn\u00e9s de tapas.<\/p>\n<p style=\"text-align: center;\">Envolez-vous vers une <strong>destination surprise<\/strong> avec <a href=\"https:\/\/waynabox.com\/blog\/fr?utm_source=facebook&amp;utm_medium=post&amp;utm_campaign=FR_CONT_blog_rooftops\">Waynabox<\/a> ! Et qui sait, peut-\u00eatre que vous pourrez profiter d&#8217;une de ces vues exceptionnelles&#8230; \ud83d\ude00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9t\u00e9 est enfin l\u00e0 ! Il est donc temps de profiter des longues soir\u00e9es estivales et des derniers rayons de soleil entre amis autour d&#8217;un petit verre. Et pour cela, on s&#8217;offre m\u00eame le luxe de s&#8217;offrir un panorama magnifique sur les plus belles villes d&#8217;Europe. D\u00e9couvrez nos meilleures adresses des plus beaux rooftops. Lisbonne [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-3284","post","type-post","status-publish","format-standard","hentry","category-voyage-parfait-fr"],"_links":{"self":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/3284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=3284"}],"version-history":[{"count":2,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/3284\/revisions"}],"predecessor-version":[{"id":15698,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/3284\/revisions\/15698"}],"wp:attachment":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=3284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=3284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=3284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}