{"id":3613,"date":"2016-11-16T09:00:09","date_gmt":"2016-11-16T07:00:09","guid":{"rendered":"http:\/\/blog.waynabox.com\/?p=3613"},"modified":"2019-02-12T08:23:50","modified_gmt":"2019-02-12T08:23:50","slug":"lexperience-bea-porto","status":"publish","type":"post","link":"https:\/\/waynabox.com\/blog\/fr\/2016\/11\/16\/lexperience-bea-porto\/","title":{"rendered":"L&#8217;exp\u00e9rience de Bea \u00e0 Porto"},"content":{"rendered":"<p style=\"text-align: right;\"><i><span style=\"font-weight: 400;\">Par Bea Lara, COO de Waynabox (traduit de l\u2019espagnol par Marion)<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">J\u2019avais tr\u00e8s envie de faire une escapade pour pouvoir me d\u00e9connecter du d\u00e9fi qui est d\u2019envoyer chaque week-end de plus en plus de wayners en voyage ! Au final, nous sommes toujours en train de pr\u00e9parer des surprises pour les autres et nous avons souvent la sensation de ne pas avoir le temps pour voyager\u2026 J\u2019ai donc d\u00e9cid\u00e9 d\u2019organiser une aventure romantique \u00e0 Porto dans le pur style <a href=\"https:\/\/waynabox.com\/blog\/fr\/?utm_source=blog&amp;utm_medium=post&amp;utm_content=FR_CONT_blog_bea\">Waynabox<\/a> pour surprendre mon compagnon pour son anniversaire. \u201cPr\u00e9pare ta valise pour deux jours\u201d, lui ai-je dis, \u201cje passe te prendre \u00e0 5 heures du matin pour aller \u00e0 l\u2019a\u00e9roport\u201d. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Je connaissais d\u00e9j\u00e0 la destination, mais c\u2019est une ville qui a beaucoup \u00e0 offrir et qui m\u00e9rite une deuxi\u00e8me et troisi\u00e8me visite. En plus je savais que \u00e7a allait plaire \u00e0 mon compagnon. A Porto il y a l\u2019art, la culture, l\u2019histoire et une gastronomie riche \u00e0 prix plus qu\u2019accessibles. Sa taille est parfaite pour la parcourir \u00e0 pieds et on peut visiter et d\u00e9couvrir beaucoup de coins charmants en quelques jours. Voil\u00e0 pourquoi j\u2019ai voulu partager mon exp\u00e9rience pour vous donner\u00a0une id\u00e9e de ce qu\u2019on peut faire lors d\u2019une courte escapade dans une jolie ville portugaise. <\/span><\/p>\n<h2><b>Jour 1<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Comme je l\u2019ai dit, notre vol \u00e9tait un peu t\u00f4t. Au Portugal il y a une heure de moins, comme aux Canaries, ce qui nous a fait arriver tr\u00e8s t\u00f4t \u00e0 Sa Carneiro, l\u2019a\u00e9roport qui se trouve \u00e0 30 minutes de la ville en transport en commun. Il est bien connect\u00e9 par des bus, bien que le m\u00e9tro soit la fa\u00e7on la plus commode et pratique de se rendre au centre. Selon o\u00f9 se situe l\u2019h\u00f4tel il y a plusieurs arr\u00eats centriques: Trindade, Casa da M\u00fasica\u2026 Notre arr\u00eat \u00e9tait Bolh\u00e3o. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous n\u2019avons pas utilis\u00e9 le transport public une autre fois pendant le voyage, m\u00eame si je vous recommande de prendre le tramway touristique ou un v\u00e9lo, car selon mes calculs nous avons march\u00e9 une dizaine de kilom\u00e8tres le premier jour et une quinzaine le second. Cependant nous avons aussi bien mang\u00e9 pour tenir ces distances et plus, les balades dans Porto ont \u00e9t\u00e9 une sorte de th\u00e9rapie anti-calories. Tout ce que nous avons essay\u00e9 me semblait absolument d\u00e9licieux. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous commen\u00e7ons avec un petit-d\u00e9jeuner copieux compos\u00e9 de <\/span><i><span style=\"font-weight: 400;\">pasteis de nata<\/span><\/i><span style=\"font-weight: 400;\"> (qui sont en r\u00e9alit\u00e9 remplis de cr\u00e8me), des friands et des petites brioches recouvertes de sucre glace le tout accompagn\u00e9 d\u2019un caf\u00e9 con leche. La matin\u00e9e \u00e9tait pluvieuse et grise, et la premi\u00e8re chose qui a attir\u00e9 notre attention ont \u00e9t\u00e9 les rues pav\u00e9es et plomb\u00e9es et les fa\u00e7ades couvertes de carreaux. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Capela das Almas de Santa Caterina est un bon exemple, couverte avec de carreaux bleus et blancs avec des images de la vie de Sainte de haut en bas. Nous sommes rentr\u00e9s la visiter et nous nous sommes dit qu\u2019il y a avait beaucoup de monde pour une heure si matinale, 7h. Porto a ce charme d\u00e9cadent de l\u2019Espagne post-guerre. C\u2019est aussi une ville moderne, avec un grand mouvement artistique et culturel entre les jeunes, mais qui se combine avec une soci\u00e9t\u00e9 traditionnelle et un certain air ancien, ce qui lui rend Porto une destination parfaite pour se relaxer et d\u00e9connecter.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3615\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-3-720x450.jpg\" alt=\"oporto-bea-3\" width=\"800\" height=\"600\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-3-300x225.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-3-1030x773.jpg 1030w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-3-768x576.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-3-1536x1152.jpg 1536w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-3-601x450.jpg 601w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-3.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Nous avons laiss\u00e9 nos sacs \u00e0 l\u2019h\u00f4tel, un de nos pr\u00e9f\u00e9r\u00e9s de la ville et avec lequel nous avons un accord avec Waynabox pour pouvoir envoyer plus de voyageurs. Situ\u00e9 sur la Pla\u00e7a da Batalha, au centre de Porto, en face de l&#8217;\u00e9glise San Ildefonso et du Th\u00e9\u00e2tre National, il a \u00e9t\u00e9 s\u00e9lectionn\u00e9 cette ann\u00e9e par le Travellers Choice Award. Comme l\u2019h\u00f4tel \u00e9tait plein, le <\/span><i><span style=\"font-weight: 400;\">checkin<\/span><\/i><span style=\"font-weight: 400;\"> ne s\u2019est pas fait avant les 14h et nous avions plus de 6 heures devant nous pour visiter la ville, nous avons donc d\u00e9cid\u00e9 de parcourir tout le centre historique. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous avons commenc\u00e9 par la Cath\u00e9drale et le Mus\u00e9e d\u2019Art Sacr\u00e9. A cette heure-ci nous les avons trouv\u00e9 ferm\u00e9s mais le bon c\u00f4t\u00e9 a \u00e9t\u00e9 que nous pouvions faire des photos sans aucun autre touriste. Nous sommes all\u00e9s au Monast\u00e8re de San Bento da Vit\u00f3ria, qui est class\u00e9 patrimoine de l\u2019humanit\u00e9 et qui se visite uniquement avec un guide. Des visites sont organis\u00e9es chaque jour \u00e0 midi pour seulement 3\u20ac. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous avons continu\u00e9 jusqu\u2019au Centre Portugais de Photographie. Le b\u00e2timent qui h\u00e9berge ce centre, dont l\u2019entr\u00e9e est gratuite, est une ancienne prison et nous avons pu voir une int\u00e9ressante collection de photos portugaises mais aussi des pi\u00e8ces d\u2019Henri Cartier Bresson ou Sebastian Salgado. Nous nous sommes balad\u00e9s dans des parcs environnants, par lesquels passe l\u2019ancien tramway, et nous avons aussi visit\u00e9 la Torre dos Clerigos. Dans cette m\u00eame rue il y a beaucoup de caf\u00e9t\u00e9rias et boutiques touristiques o\u00f9 nous avons d\u00e9cid\u00e9 d\u2019essayer la \u201cportuguese experience\u201d \u00e0 la Casa Portuguesa dos Bolinhos de Bacalhau, o\u00f9 la sp\u00e9cialit\u00e9 sont les d\u00e9licieuses croquettes remplies de fromage accompagn\u00e9es de Porto. <\/span><\/p>\n<figure id=\"attachment_3616\" aria-describedby=\"caption-attachment-3616\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-3616\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Castillo-Bea-720x450.jpg\" alt=\"oporto-castillo-bea\" width=\"800\" height=\"427\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Castillo-Bea-300x160.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Castillo-Bea-1030x550.jpg 1030w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Castillo-Bea-768x410.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Castillo-Bea-1536x820.jpg 1536w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Castillo-Bea.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-3616\" class=\"wp-caption-text\">Le Monast\u00e8re de San Bento da Vitoria<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3617\" aria-describedby=\"caption-attachment-3617\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-3617\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-1-720x450.jpg\" alt=\"whatsapp-image-20160517-1\" width=\"800\" height=\"600\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-1-300x225.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-1-1030x773.jpg 1030w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-1-768x576.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-1-1536x1152.jpg 1536w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-1-601x450.jpg 601w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-1.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-3617\" class=\"wp-caption-text\">Notre d\u00eener du premier jour a \u00e9t\u00e9 cette spectaculaire Francesinha, un sandwichrempli de viande (ou de tofu, dans mon cas), couvert de fromage, oeuf et sauce piquante \u00e0 la bi\u00e8re<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Apr\u00e8s le d\u00e9jeuner nous sommes all\u00e9s \u00e0 l\u2019h\u00f4tel, nous repos\u00e9s de notre r\u00e9veil matinal et de notre promenade. Le soir nous nous sommes dirig\u00e9s vers le march\u00e9 de Bolh\u00e3o, et nous sommes pass\u00e9s devant le caf\u00e9 Majestic, un joli caf\u00e9 moderne qui est toujours pareil depuis le XIX\u00e8me si\u00e8cle. Trouv\u00e9 une table est plut\u00f4t difficile car c\u2019est un lieu tr\u00e8s touristique. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Une bonne alternative pour recr\u00e9er l\u2019exp\u00e9rience de se trouver dans une autre \u00e9poque est le caf\u00e9 Imperial, sur Aliados, reconverti en McDonalds, mais qui a conserv\u00e9 sa d\u00e9coration originale et est un exemple de plus de ce m\u00e9lange ancien et moderne qui me fascine \u00e0 Porto. Des cuisses de poulet, des empanadillas de crevette et des croquettes de viandes qui selon mon compagnon \u00e9taient spec-ta-cu-lai-res. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous avons accompagn\u00e9 le tout de SuperBock, la bi\u00e8re locale. Dans cette zone, Santa Teresa, il y a beaucoup de bars et restaurants, mais nous avions une mission. Trouvez la meilleure francesinha de Porto. Ce plat typique (sandwich rempli de viande et couvert de fromage, d\u2019un oeuf et d\u2019une sauce \u00e0 la bi\u00e8re et tomate l\u00e9g\u00e8rement piquante) se trouve dans plusieurs restaurants qui disent avoir la recette originale et bien s\u00fbr le brevet. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Deux de ceux qu\u2019on trouve dans la rue de Passos Manuel en face du Colis\u00e9e, nous ont plu. Je crois que le Caf\u00e9 Santiago est sans doute le meilleur endroit pour l\u2019essayer, mais nous sommes all\u00e9s chez la concurrence, Lado B, qui avait une table de libre et une version v\u00e9g\u00e9tarienne de la francesinha \u00e0 laquelle je n\u2019ai pas pu r\u00e9sister. <\/span><\/p>\n<h2><b>Jour 2.<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Le matin suivant nous voulions visiter toute la zone de la ville qui se trouve aux bords du fleuve Douro et la ville voisine Vila Nova de Gaia, o\u00f9 l\u2019on trouve les bodegas qui fabriquent le c\u00e9l\u00e8bre vin de Porto. Nous avons travers\u00e9 le majestueux pont de fer Luis I et nous avons pu profiter des belles vues sur la ville depuis l\u2019autre c\u00f4t\u00e9. La partie du port fluvial est tr\u00e8s belle, avec ses petites maisons de couleurs avec les premiers rayons de soleil, les b\u00e2teaux traversant le fleuve, et un sans fin de petits bars et boutiques o\u00f9 on entend toujours de la musique typique portugaise.<\/span><\/p>\n<figure id=\"attachment_3618\" aria-describedby=\"caption-attachment-3618\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3618\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160516-1-720x450.jpg\" alt=\"whatsapp-image-20160516-1\" width=\"800\" height=\"585\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160516-1-300x219.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160516-1-1030x753.jpg 1030w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160516-1-768x562.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160516-1.jpg 1466w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-3618\" class=\"wp-caption-text\">Les petites maisons de Vilanova de Gaia<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Nous avons parcouru tout le bord du fleuve, car notre intention \u00e9tait d\u2019arriver \u00e0 l\u2019embouchure et de voir les plages d\u2019Atlantique. Les plus de 8 kilom\u00e8tres parcourus en valaient la peine. Nous avons mang\u00e9 une soupe verte et <\/span><i><span style=\"font-weight: 400;\">bacalhau com natas<\/span><\/i><span style=\"font-weight: 400;\"> (au four avec un gratin cr\u00e9meux) en face du b\u00e2timent de l\u2019ancienne douane ou Alf\u00e2ndega, sur une petite place remplie de restaurants typiques avec des menus du jour qui incluent le pain et la boisson en plus de deux plats pour six euros ! <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous avons continu\u00e9 vers le quartier de Miragaia, en passant par le mus\u00e9e du vin, jusqu\u2019\u00e0 traverser le pont de Arrabida, point \u00e0 partir duquel le Douro s\u2019\u00e9largit pour arriver \u00e0 l\u2019oc\u00e9an. Il y avait de petits rochers avec pleins de mouettes et autres oiseaux marins et d\u2019eau douce, beaucoup p\u00eacheurs, et peu \u00e0 peu nous avons commenc\u00e9 \u00e0 voir moins de pierres et plus de sable, jusqu\u2019\u00e0 passer le phare et arriver aux plages. Nous avons continu\u00e9 \u00e0 nous balader jusqu\u2019\u00e0 la soir\u00e9e -bien avanc\u00e9e-, nous nous sommes arr\u00eat\u00e9s prendre un caf\u00e9 bien m\u00e9rit\u00e9 en face de la mer, et sur le rond point qui est connect\u00e9 \u00e0 l\u2019Avenue Boa Vista nous faisions demi-tour pour rentrer dans le centre. <\/span><\/p>\n<figure id=\"attachment_3619\" aria-describedby=\"caption-attachment-3619\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3619\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-720x450.jpg\" alt=\"whatsapp-image-20160517\" width=\"800\" height=\"600\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-300x225.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-1030x773.jpg 1030w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-768x576.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-1536x1152.jpg 1536w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517-601x450.jpg 601w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/WhatsApp-Image-20160517.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-3619\" class=\"wp-caption-text\">L&#8217;Atlantique !<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Nous aurions pu prendre le bus, mais nous avons d\u00e9cid\u00e9 de traverser le parc de la ville et nous sommes descendus par le Mus\u00e9e d\u2019Art Contemporain de Serralves jusqu\u2019au jardin botanique. Nous avons vu que nous \u00e9tions tr\u00e8s pr\u00e8s d\u2019un b\u00e2timent curieux, une synagogue, et nous nous sommes approch\u00e9s pour la voir. Il parait qu\u2019il y a une grande communaut\u00e9 juive \u00e0 Porto. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous avons continu\u00e9 jusqu\u2019\u00e0 l\u2019avenue Boa Vista de nouveau, \u00e0 la Place de Albuquerque, o\u00f9 l\u2019on trouve le b\u00e2timent moderne de Casa da M\u00fasica, et je me suis souvenue pas loin il y a avait un march\u00e9, dans la Rua do Bom Sucesso, o\u00f9 il y a beaucoup de petites \u00e9choppes pour manger et nous avons d\u00e9cid\u00e9 de d\u00eener ici. Nous avons essay\u00e9 les <\/span><i><span style=\"font-weight: 400;\">rissois<\/span><\/i><span style=\"font-weight: 400;\"> ou empanadillas, de diff\u00e9rents go\u00fbts, tr\u00e8s riches, et une chose moins typique des \u201csliders\u201d ou mini hamburgers d\u2019une boutique locale. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apr\u00e8s d\u00eener et v\u00e9ritablement fatigu\u00e9s, nous nous sommes dirig\u00e9s vers l\u2019h\u00f4tel de nouveau, bien que si nous n\u2019avions pas tant march\u00e9 nous aurions pu nous rendre dans les nombreux bars aux alentours qui proposent de la musique portugaise en direct et que nous avions tr\u00e8s envie d\u2019\u00e9couter. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le matin suivant apr\u00e8s le <\/span><i><span style=\"font-weight: 400;\">check out<\/span><\/i><span style=\"font-weight: 400;\">, nous partions de Porto, une ville tr\u00e8s proche mais aussi myst\u00e9rieuse et distincte, comme retenue dans le temps tout en \u00e9tant actuelle, nous y retournerons sans aucun doute.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3620\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-2-720x450.jpg\" alt=\"oporto-bea-2\" width=\"800\" height=\"450\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-2-300x169.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-2-1030x579.jpg 1030w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-2-768x432.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-2-1536x864.jpg 1536w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-2-1024x576.jpg 1024w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2016\/11\/Oporto-Bea-2.jpg 1599w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par Bea Lara, COO de Waynabox (traduit de l\u2019espagnol par Marion) J\u2019avais tr\u00e8s envie de faire une escapade pour pouvoir me d\u00e9connecter du d\u00e9fi qui est d\u2019envoyer chaque week-end de plus en plus de wayners en voyage ! Au final, nous sommes toujours en train de pr\u00e9parer des surprises pour les autres et nous avons [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[36],"tags":[],"class_list":["post-3613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-experiences-waynabox"],"_links":{"self":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/3613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=3613"}],"version-history":[{"count":5,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/3613\/revisions"}],"predecessor-version":[{"id":15790,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/3613\/revisions\/15790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/media\/3614"}],"wp:attachment":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=3613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=3613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=3613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}