{"id":4927,"date":"2017-06-22T13:44:58","date_gmt":"2017-06-22T11:44:58","guid":{"rendered":"http:\/\/blog.waynabox.com\/?p=4927"},"modified":"2019-02-12T09:03:10","modified_gmt":"2019-02-12T09:03:10","slug":"cet-ete-surprenez-vous-avec-le-vin-gik-et-gagnez-voyage-surprise-waynabox","status":"publish","type":"post","link":"https:\/\/waynabox.com\/blog\/fr\/2017\/06\/22\/cet-ete-surprenez-vous-avec-le-vin-gik-et-gagnez-voyage-surprise-waynabox\/","title":{"rendered":"Cet \u00e9t\u00e9 surprenez-vous avec le vin g\u00efk et&#8230; Gagnez un voyage surprise Waynabox!"},"content":{"rendered":"<p>Nous souhaitons accueillir l&#8217;\u00e9t\u00e9 d&#8217;une mani\u00e8re toute particuli\u00e8re cette ann\u00e9e. Vous savez que chez Waynabox on adore les surprises et vous aidez \u00e0 organiser les meilleures vacances d&#8217;\u00e9t\u00e9 possibles&#8230; On sait que &#8220;vacances d&#8217;\u00e9t\u00e9&#8221; rime avec ap\u00e9ros, soleil et playa. Et il semblerait que <a href=\"https:\/\/giklive.fr\/?utm_source=blog&amp;utm_campaign=waynabox&amp;utm_content=CONT_blog_waynabox\">G\u00efk Live<\/a> ait rassembl\u00e9 tout ce qu&#8217;on aimait: existe-t-il quelque chose de plus surprenant qu&#8217;un vin bleu ?<\/p>\n<p>Apr\u00e8s avoir d\u00e9gust\u00e9 quelques bouteilles de ce d\u00e9licieux breuvage, provenant de vignes espagnoles et aux ar\u00f4mes fruit\u00e9s qui s&#8217;associent \u00e0 la perfection avec n&#8217;importe quel diner entre amis: on est FANS. Alors oui c&#8217;est surprenant, mais on a encore plus surprenant: d\u00e9guster d&#8217;une coupe de vin bleu et s&#8217;\u00e9chapper vers une destination SURPRISE d\u00e9couverte deux jours avant de voyager. Et le tout, gratos !<\/p>\n<div id='gallery-1' class='gallery galleryid-4927 gallery-columns-3 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/waynabox.com\/blog\/fr\/cuba1-2\/'><img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba1.jpg 1536w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba1-300x200.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba1-768x512.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba1-1024x683.jpg 1024w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/waynabox.com\/blog\/fr\/cuba2-2\/'><img decoding=\"async\" width=\"1536\" height=\"1024\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba2.jpg 1536w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba2-300x200.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba2-768x512.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/cuba2-1024x683.jpg 1024w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/waynabox.com\/blog\/fr\/germany-1-2\/'><img decoding=\"async\" width=\"1251\" height=\"832\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-1.jpg 1251w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-1-300x200.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-1-768x511.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-1-1024x681.jpg 1024w\" sizes=\"(max-width: 1251px) 100vw, 1251px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/waynabox.com\/blog\/fr\/germany-2-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"1537\" height=\"1025\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-2.jpg 1537w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-2-300x200.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-2-768x512.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/germany-2-1024x683.jpg 1024w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/waynabox.com\/blog\/fr\/marruecos-1-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"4368\" height=\"2912\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/marruecos-1-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/waynabox.com\/blog\/fr\/marruecos-2-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/marruecos-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/marruecos-2.jpg 1620w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/marruecos-2-300x200.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/marruecos-2-768x512.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2017\/06\/marruecos-2-1024x683.jpg 1024w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Si vous \u00eates un amateur de vin, keep reading, parce que voici notre derni\u00e8re collaboration de juin. Pour l&#8217;achat de 3 bouteilles de G\u00efk vous participerez au concours pour gagner un voyage Waynabox pour deux personnes. Ca vous tente? En plus c&#8217;est tr\u00e8s simple :<\/p>\n<p>1) Faites un achat de minimum 3 bouteilles\u00a0<a href=\"https:\/\/giklive.fr\/?utm_source=blog&amp;utm_campaign=waynabox&amp;utm_content=CONT_blog_waynabox\">ici<\/a>.<br \/>\n2) Remplissez le questionnaire sur cette page.<br \/>\n3)\u00a0Cliquez sur participer et c&#8217;est fait !<\/p>\n<p>Vous pouvez participer jusqu&#8217;au 23\/07\/2017 et les r\u00e9servations accept\u00e9es pour participer devront \u00eatre r\u00e9alis\u00e9es entre le 22\/06 et le 23\/07. Le 24 juillet le nom du gagnant du voyage sera annonc\u00e9 \ud83d\ude42 \u00a0?<\/p>\n<p>Bonne chance et\u00a0tchin, tchin!<\/p>\n<h2>. . .<\/h2>\n<p>&nbsp;<\/p>\n<h3>Bases L\u00e9gales \u201cAchetez 3 bouteilles de\u00a0Gik et gagnez un voyage Waynabox\u201d<\/h3>\n<p>*Ce concours n&#8217;est ni sponsoris\u00e9, ni administr\u00e9, ni promu par, ou en collaboration, avec Facebook et\/ou Instagram.<\/p>\n<ol>\n<li>Organisation: L&#8217;emprise qui organise cette action promotionnelle est\u00a0WAYNA AERO SL, avec CIF: B-98649247, et GIK LIVE SL avec CIF:\u00a0B95819736<\/li>\n<\/ol>\n<ol start=\"2\">\n<li>Dates de promotion:\u00a0La campagne commence le 22\/06\/2017 \u00e0 14h et se terminera le 23\/07\/2017\u00a0\u00e0 23h59.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li>Participation:\u00a0La participation se r\u00e9alise \u00e0 travers la page web\u00a0http:\/\/pre.waynabox.com\/eteavecgik\/. Pour participer, les utilisateurs devront suivre les indications sur la dite page et remplir le formulaire avec les champs requis.<\/li>\n<\/ol>\n<p>Seules les personnes majeures peuvent participer. Les employ\u00e9s ou collaborateurs de Waynabox et Gik Live ou leurs proches directs ne pourront pas participer.<\/p>\n<ol start=\"4\">\n<li>M\u00e9canique de la promotion:\u00a0La participation sera active du 22 juin 2017 au 23 juillet 2017 et les participants devront suivre les \u00e9tapes suivantes:<\/li>\n<\/ol>\n<ul>\n<li>R\u00e9aliser un achat minimum d&#8217;un pack de trois bouteilles de vin bleu Gik Live sur leur boutique en ligne de la marque:\u00a0https:\/\/giklive.fr\/produit\/trois-bouteilles\/<\/li>\n<li>Acc\u00e9der \u00e0 la page de participation:\u00a0http:\/\/pre.waynabox.com\/eteavecgik\/<\/li>\n<li>Remplir le formulaire avec le Pr\u00e9nom, Nom, E-Mail et num\u00e9ro de commande de l&#8217;achat sur Gik Live<\/li>\n<li>N&#8217;il n&#8217;y a pas de limite de participation<\/li>\n<\/ul>\n<p>Le gagnant sera choisi al\u00e9atoirement selon le nombre de participant et en ayant rempli correctement toutes les \u00e9tapes de la participation.<\/p>\n<ol start=\"5\">\n<li>Prix: Le prix consiste en 1 voyage Waynabox pour deux personnes vers une destination surprise, vols aller-retour et deux nuits d&#8217;h\u00e9bergement. La r\u00e9servation doit \u00eatre r\u00e9alis\u00e9e entre le 1er ao\u00fbt 2017 et le 1er ao\u00fbt 2018, selon les dates disponibles sur waynabox.com\/fr.<\/li>\n<\/ol>\n<p>C&#8217;est un prix personnel et non transf\u00e9rable. Une fois la r\u00e9servation faite, il ne sera pas possible de changer la date.<\/p>\n<ol start=\"6\">\n<li>Gagnant: Le gagnant sera choisit al\u00e9atoirement selon le nombre de participant et en ayant rempli correctement toutes les \u00e9tapes de la participation via le site <a href=\"https:\/\/www.random.org\/\">random.org<\/a>.<\/li>\n<\/ol>\n<ol start=\"7\">\n<li>Publication du gagnant:\u00a0La notification et la publication du gagnant sera r\u00e9alis\u00e9e les 15 prochains jours apr\u00e8s la r\u00e9alisation du tirage au sort \u00e0 travers les r\u00e9seaux de Waynabox et de Gik Live.<\/li>\n<\/ol>\n<p>Le gagnant accepte que son nom soit publi\u00e9 sur tous les profils des r\u00e9seaux sociaux de Waynabox et de Gik Live.<\/p>\n<ol start=\"8\">\n<li>Livraison du prix:\u00a0Waynabox contactera le gagnant pour lui donner son prix. Une fois que le gagnant aura choisit la p\u00e9riode pendant laquelle voyager, le gagnant pourra choisir les dates disponibles sur la page Waynabox. Le gagnant r\u00e9servera la date sur le site et Waynabox g\u00e8rera la r\u00e9servation.<\/li>\n<\/ol>\n<p>Le gagnant pourra renoncer au prix, mais ne pourra en aucun cas l&#8217;\u00e9changer contre de l&#8217;argent.<\/p>\n<ol start=\"9\">\n<li>Traitement des donn\u00e9es: Conform\u00e9ment \u00e0 la Loi Organique 15\/1999 du 13 d\u00e9cembre sur La Protection des Donn\u00e9es \u00e0 Caract\u00e8res Personnelles et le D\u00e9cret R\u00e9el\u00a01720\/2007 du 21 d\u00e9cembre nous informons aux participants que les donn\u00e9es pourront \u00eatre incorpor\u00e9s dans les fichiers automatis\u00e9s de Waynabox et de Gik Live.<\/li>\n<\/ol>\n<p>La simple participation au concours implique l&#8217;acception des pr\u00e9sentes Bases.<\/p>\n<ol start=\"10\">\n<li>L\u00e9gislation applicable: Ce concours se soumettra \u00e0 la norme espagnol applicable.<\/li>\n<\/ol>\n<ol start=\"11\">\n<li>Acceptation des bases: le fait de participer \u00e0 cette promotion implique la totale acception des pr\u00e9sentes bases.<\/li>\n<\/ol>\n<ol start=\"12\">\n<li>\n<div class=\"_2cuy _3dgx _2vxa\"><span class=\"_4yxo\">R\u00e9servations et limitations: <\/span>Waynabox se r\u00e9serve le droit d\u2019effectuer des changements qui pourraient g\u00e9n\u00e9rer des probl\u00e8mes quant \u00e0 la bonne r\u00e9alisation du concours quand sont rassembl\u00e9es une cause juste ou bien un cas de force majeur qui empecherait de finaliser la forme expos\u00e9es dans les pr\u00e9sentes bases. Waynabox se r\u00e9serve le droit de reporter ou d\u2019\u00e9tendre la p\u00e9riode du concours comme la facult\u00e9 d\u2019interpr\u00e9ter les pr\u00e9sentes bases l\u00e9gales. Waynabox se r\u00e9serve le droit de r\u00e9soudre selon son interpr\u00e9tation certains aspects non \u00e9mis dans ces bases. &#8211; Le gain est personnel, non transf\u00e9rable et ne peut-\u00eatre chang\u00e9 en aucune circonstance par de l\u2019argent en esp\u00e8ce ou en autre biens ou services. Le gain est unique et exclusif avec les \u00e9l\u00e9ments indiqu\u00e9s dans les pr\u00e9sents Termes et Conditions.<\/div>\n<\/li>\n<li>\n<div class=\"_2cuy _3dgx _2vxa\"><span class=\"_4yxo\">Autres normes d\u2019usage: <\/span>Ne sont pas admis de commentaires offensifs, insultes, menaces, langage malhonn\u00eate, contenus d\u00e9gradants ou d\u00e9sobligeants envers d\u2019autres membres de la communaut\u00e9 ou envers nos produits et services, marque ou notre \u00e9quipe. &#8211; Les pr\u00e9sents Termes et Conditions se r\u00e9gissent conform\u00e9ment \u00e0 la loi espagnole. En cas de divergence entre les versions des Termes et Conditions pr\u00e9vaudra les pr\u00e9sents Termes et Conditions, r\u00e9dig\u00e9s en Fran\u00e7ais. Les pr\u00e9sents Termes et Conditions s\u2019appliqueront aux participants sans pr\u00e9judices se r\u00e9f\u00e9rant \u00e0 la l\u00e9gislation applicable qui ne pourrait leur correspondre.<\/div>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Nous souhaitons accueillir l&#8217;\u00e9t\u00e9 d&#8217;une mani\u00e8re toute particuli\u00e8re cette ann\u00e9e. Vous savez que chez Waynabox on adore les surprises et vous aidez \u00e0 organiser les meilleures vacances d&#8217;\u00e9t\u00e9 possibles&#8230; On sait que &#8220;vacances d&#8217;\u00e9t\u00e9&#8221; rime avec ap\u00e9ros, soleil et playa. Et il semblerait que G\u00efk Live ait rassembl\u00e9 tout ce qu&#8217;on aimait: existe-t-il quelque chose [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":4913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[41],"tags":[],"class_list":["post-4927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsevents"],"_links":{"self":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=4927"}],"version-history":[{"count":4,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4927\/revisions"}],"predecessor-version":[{"id":15840,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/4927\/revisions\/15840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/media\/4913"}],"wp:attachment":[{"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=4927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=4927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=4927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}