{"id":19422,"date":"2019-05-27T08:22:30","date_gmt":"2019-05-27T08:22:30","guid":{"rendered":"http:\/\/waynabox.com\/?p=19422"},"modified":"2020-02-28T14:06:43","modified_gmt":"2020-02-28T13:06:43","slug":"vacanza-a-lione-cose-da-vedere","status":"publish","type":"post","link":"https:\/\/waynabox.com\/blog\/it\/2019\/05\/27\/vacanza-a-lione-cose-da-vedere\/","title":{"rendered":"Vacanza a Lione? Ecco 5 cose da vedere assolutamente"},"content":{"rendered":"<p>Scegliere una <strong>bella citt\u00e0 per una vacanza<\/strong> non \u00e8 semplice e in molti casi pensiamo che \u00e8 la destinazione pi\u00f9 lontana la migliore. Non \u00e8 cos\u00ec e un chiaro esempio \u00e8 la <strong>citt\u00e0 di Lione in Francia<\/strong>. A poche ore di distanza dal confine con l&#8217;Italia, \u00e8 una localit\u00e0 che vale la pena di visitare in un week end fuori porta perch\u00e9 si tratta di una citt\u00e0 antica in cui il primo insediamento risale a circa 2000 anni fa.<\/p>\n<p>Non solo, organizzando delle <a href=\"\/\/waynabox.com\/it\/2019\/07\/19\/sorprese-per-il-compleanno-la-guida-alla-festa-perfetta\/\">sorprese per una festa di complenno<\/a> e l&#8217;idea \u00e8 quella di regalare un viaggio, questa citt\u00e0 \u00e8 una valida candidata. Prima di tutto, perch\u00e9 \u00e8 possibile visitarla in un week end ed \u00e8 perfetta per assaggiare la gastronomia francese.<\/p>\n<h2>Cosa visitare a Lione in due giorni?<\/h2>\n<p>Se sei prossimo a partire la tua destinazione \u00e8 questa citt\u00e0 francese, sicuramente ti sei gi\u00e0 chiesto <a href=\"\/\/www.lemozionediunviaggio.it\/2018\/03\/29\/cosa-vedere-a-lione-8-punti-di-interesse-da-non-perdere-nella-citta-delle-luci\/\" target=\"_blank\" rel=\"noopener noreferrer\">cosa vedere a Lione<\/a> e quali luoghi di interesse vale la pena visitare. Per questa occasione, Waynabox e il <strong>travel blog l&#8217;Emozione di un viaggio<\/strong> hanno collaborato per stilare una <strong>lista delle migliori cose da visitare<\/strong> in questa citt\u00e0 francese, come chiese, monumenti, musei, quartieri tipici o semplicemente delle passeggiate lungo i ponti sui fiumi che toccano questa citt\u00e0 sono solo alcune delle cose da fare.<\/p>\n<p>Non solo, la <strong>citt\u00e0 \u00e8 famosa anche per la gastronomia<\/strong> e non puoi perderti alcune cose da mangiare come i formaggi locali, l&#8217;Andouillette\u00a0 o le rosette di Lyon (quest&#8217;ultimi due sono insaccati). \ud83d\ude42<\/p>\n<p>Questa destinazione \u00e8 anche una valida alternativa per regalare un viaggio e se decidi di farlo non dimentare quali sono le <a href=\"\/\/waynabox.com\/it\/2019\/02\/07\/cose-belle-da-scrivere-nel-biglietto-per-un-regalo-di-viaggio\/\">cose belle da scrivere nel biglietto per un regalo di viaggio<\/a>. Tra queste, non bisogna mai dimenticare di usare un tono affettuoso e augurare il meglio alla persona che ricevere un regalo.<\/p>\n<p>Adesso scopriamo quali sono le <strong>principali cose da visitare nella citt\u00e0 di Lione<\/strong> durante un breve soggiorno in questa citt\u00e0.<\/p>\n<h3>1. La vecchia Lione o Viex Lyon<\/h3>\n<p>La <strong>parte antica di una citt\u00e0<\/strong> \u00e8 quella pi\u00f9 tipicamente storica e legata agli avvenimenti del passato in cui \u00e8 possibile visitare antichi palazzi, particolarit\u00e0 architettonica e piccole vie che si possono percorrere solo a piedi. Se non lo sapevi, il quartiere antico della citt\u00e0 di Lione \u00e8 entrato nel patrimonio dell&#8217;UNESCO.<\/p>\n<p>Un&#8217;altra particolarit\u00e0 unica di questa citt\u00e0 sono i <em>Traboules<\/em>, cio\u00e8 dei passaggi che collegano gli edifici antichi di questo quartiere. La loro costruzione risale al 1800 e avvenne per esigenze pratiche, cio\u00e8 permettere agli artigiani della seta di<strong> muoversi nel centro storico<\/strong> anche durante i giorni di pioggia. Non solo, durante l&#8217;occupazione tedesca negli anni della seconda guerra mondiale furono utilizzati dalla resistenza e dalla popolazione locale come luogo di riparo dai bombardamenti.<\/p>\n<p>Aspetta, se stai pensa di organizzare una vacanza non perderti i <a href=\"\/\/waynabox.com\/it\/2019\/02\/13\/6-consigli-pratici-per-un-viaggio-economico\/\">consigli per organizzare un viaggio economico<\/a>. Risparmiare \u00e8 semplice e ci sono molti modi per farlo, sia prima la partenza, sia durante i giorni di vacanza. Uno di questi \u00e8 quello di prenotare in anticipo di circa un mese per incontrare la tariffa aerea al miglior prezzo.<\/p>\n<figure id=\"attachment_19463\" aria-describedby=\"caption-attachment-19463\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-19463\" src=\"\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/05\/i-monumenti-storici-di-lione.jpg\" alt=\"I luoghi di interesse storico di Lione\" width=\"640\" height=\"480\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/05\/i-monumenti-storici-di-lione.jpg 640w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/05\/i-monumenti-storici-di-lione-300x225.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/05\/i-monumenti-storici-di-lione-450x338.jpg 450w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-19463\" class=\"wp-caption-text\">Michel Bertolotti | Pixebay<\/figcaption><\/figure>\n<h3>2. La cattedrale di Saint Jean<\/h3>\n<p>Un altro<strong> punto di interesse nel centro storico<\/strong> \u00e8 la cattedrale di Saint Jean ed \u00e8 considerata come un momento storico di Francia. Questo luogo sacro si distingue per alcune caratteristiche uniche, come il fatto che mescola stile gotito e romantico e che la sua costruzione \u00e8 avvenuta nell&#8217;arco di trecento anni. Inoltre, ospita anche un orologio astronomico risalente al XIV secolo, attualmente in funzione.<\/p>\n<h3>3. Mus\u00e9e des Confluences<\/h3>\n<p>La citt\u00e0 di Lione ha sia <strong>luoghi di interesse storici<\/strong> da visitare, sia attrazioni moderne. Nel 2014 \u00e8 stato inauguato il Musee des Confluences e <strong>rappresentana la Lione contemporanea<\/strong>. In questo museo \u00e8 possibile visitare collezioni di antropologie, specie animali e stili di architettura differente. Visitare questo museo \u00e8 sicuramente una must per la tua <a href=\"\/\/waynabox.com\/it\/2019\/03\/28\/vacanza-alternativa\/\">vacanza alternativa<\/a> nella citt\u00e0 di Lione.<\/p>\n<h3>4. Collina di Fourvi\u00e9re<\/h3>\n<p>La Collina di Fourvi\u00e9re \u00e8 una delle zone pi\u00f9 tipiche di Lione perch\u00e9 in passato ospitava le botteghe degli artigiani che lavoravano la seta. Per raggiungerla \u00e8 possibile utilizzare la funivia che parte dalla <strong>stazione della metropolitana di Vieux Lyon<\/strong> e ammirare il panorama sulla citt\u00e0. Aspetta, ma qual \u00e8 l&#8217;orario perfetto per visitarla? Il momento migliore \u00e8 durante i giorni di sole perch\u00e9 \u00e8 possibile amminare le Alpi e il monte Bianco all&#8217;orizzonte!<\/p>\n<figure id=\"attachment_19458\" aria-describedby=\"caption-attachment-19458\" style=\"width: 640px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"size-full wp-image-19458\" src=\"\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/05\/i-ponti-di-lione.jpg\" alt=\"I ponti di Lione sul Rodano\" width=\"640\" height=\"426\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/05\/i-ponti-di-lione.jpg 640w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/05\/i-ponti-di-lione-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-19458\" class=\"wp-caption-text\">Foto di loic Tijsse lingda | Pixabay<\/figcaption><\/figure>\n<h3>5. Passeggiare lungo i ponti del Rodano e Sa\u00f4ne<\/h3>\n<p>Lione, e la Francia in generale, sono <strong>destinazioni perfette per i viaggi di coppia<\/strong>. Questa citt\u00e0 francese \u00e8 toccata da due fiumi, il Rodano e il Sa\u00f4ne, e una delle cose da fare \u00e8 quella di passeggiare sui ponti al tramonto ammirando la mescola di colori che avvolgono la citt\u00e0.<\/p>\n<p>Lione \u00e8 una citt\u00e0 famosa anche per la cucina e se non lo sapevi, qui \u00e8 ancora in uso l&#8217;antica tradizione del Bouchon. In molti ristoranti troverai l&#8217;arredo tipico in legno scuro tavoli con tovaglie a quadretti sulle quali potrai provare alcuni dei migliori piatti della cucina liones. Ci sono tanti ristoranti con e in questo articolo dedicato a <a href=\"https:\/\/travellairs.it\/europa\/francia\/lione\/dove-e-cosa-mangiare-a-lione\/\">dove mangiare a Lione<\/a> potrai trovare suggerimenti su bar, zone da frequentare e i migliori piatti da provare.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il tuo prossimo viaggio sar\u00e0 a Lione? Scopri quali sono le principali cose da vedere trascorri alcuni giorni di tranquillit\u00e0 in questa citt\u00e0 francese.<\/p>\n","protected":false},"author":20,"featured_media":19497,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"Vacanza a Lione? Ecco 5 cose da visitare assolutamente ","_seopress_titles_desc":"Il tuo prossimo viaggio sar\u00e0 a Lione? Scopri quali sono le principali cose da vedere trascorri alcuni giorni di tranquillit\u00e0 in questa citt\u00e0 francese.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[1269],"tags":[1324,1323],"class_list":["post-19422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guide-turistiche","tag-francia-it","tag-lione"],"_links":{"self":[{"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/posts\/19422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=19422"}],"version-history":[{"count":13,"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/posts\/19422\/revisions"}],"predecessor-version":[{"id":87915,"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/posts\/19422\/revisions\/87915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/media\/19497"}],"wp:attachment":[{"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=19422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=19422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=19422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}