{"id":16545,"date":"2019-02-26T09:24:21","date_gmt":"2019-02-26T09:24:21","guid":{"rendered":"http:\/\/waynabox.com\/?p=16545"},"modified":"2019-11-27T14:21:00","modified_gmt":"2019-11-27T13:21:00","slug":"11-lugares-imperdiveis-para-conhecer-em-madrid","status":"publish","type":"post","link":"https:\/\/waynabox.com\/blog\/pt-pt\/2019\/02\/26\/11-lugares-imperdiveis-para-conhecer-em-madrid\/","title":{"rendered":"S\u00edtios imperd\u00edveis para conheceres em Madrid"},"content":{"rendered":"<p>Se pensas em conhecer <strong>Madrid<\/strong> \u00e9 imprescind\u00edvel que <strong>leias<\/strong> isto! Esta cidade por seu tamanho pode confundir quem a visita, por isso n\u00e3o te preocupes mais! N\u00f3s preparamos-te uma lista que ser\u00e1 de grande ajuda se este for o teu pr\u00f3ximo <strong>destino surpresa<\/strong> Waynabox.<\/p>\n<h2>Madrid o que visitar em 3 dias<\/h2>\n<p>Madrid \u00e9 uma cidade com um charme pr\u00f3prio. Suas ruas coloridas, o movimentos das pessoas e o c\u00e9u quase sempre ensolarado s\u00e3o algumas das coisas que mais encantam quem a visita. \u00c9 a capital da Espanha e possui 6,5 milh\u00f5es de habitantes na sua \u00e1rea metropolitana, sendo assim, \u00e9 considerada uma das maiores cidades europeias. Mas chega de detalhes e vamos come\u00e7ar com a nossa lista:<\/p>\n<p>N\u00e3o deixes de ler nossos <a href=\"\/\/waynabox.com\/pt-pt\/2017\/05\/04\/5-conselhos-escolheres-teu-companheiro-viagem\/\">5 conselhos para escolheres o teu companheiro<\/a> de viagem ideal, assim a tua escapadinha a Madrid ser\u00e1 perfeita!<\/p>\n<h3>1. Fazer a rota dos 3 museus localizados no &#8216;Paseo del Prado&#8217;<\/h3>\n<p>O Museu do Prado, o Thyssen-Bornemisza e o Museu Nacional Centro de Arte Reina Sof\u00eda s\u00e3o tr\u00eas dos principais museus da cidade e est\u00e3o localizados muito perto um do outro. Com uma rica oferta de obras e artistas estes espa\u00e7os s\u00e3o<strong> mundialmente conhecidos<\/strong> e renomados.<\/p>\n<p>O <strong>Museu do Prado<\/strong> oferece um hor\u00e1rio gr\u00e1tis de segunda a s\u00e1bado das 18h a 20h e de domingos e feriados das 17h at\u00e9 as 19h<\/p>\n<p>O <strong>Museu Nacional Centro de Arte Reina Sof\u00eda <\/strong>oferece um hor\u00e1rio gr\u00e1tis de segunda a s\u00e1bado das 19h a 21h e de domingos e feriados das 13:30h at\u00e9 as 19h<\/p>\n<p>J\u00e1 o <strong>Museu Thyssen-Bornemisza<\/strong> s\u00f3 possui um hor\u00e1rio gr\u00e1tis que \u00e9 de segunda das 12h at\u00e9 as 16h<\/p>\n<figure id=\"attachment_16578\" aria-describedby=\"caption-attachment-16578\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-16578 size-medium\" src=\"\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/@museoreinasofia-300x300.jpg\" alt=\"vistar em madrid\" width=\"300\" height=\"300\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/@museoreinasofia-300x300.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/@museoreinasofia-80x80.jpg 80w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/@museoreinasofia.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-16578\" class=\"wp-caption-text\">Photo by @museoreinasofia on Instagram<\/figcaption><\/figure>\n<h3>2. Ir ao centro cultural &#8216;Matadero&#8217;<\/h3>\n<p>Este centro cultural que na verdade \u00e9 um antigo matadouro, mudou suas atividades a partir do ano 2006 depois de ser reformado e readaptado para receber em seu espa\u00e7o diversos <strong>eventos<\/strong> e<strong> festivais<\/strong>. Aproveita um dia de sol para conheceres os diversos cantos e surpresas que este local tem para oferecer-te.<\/p>\n<h3>3. Ir ao Pal\u00e1cio Real<\/h3>\n<p>Uma visita neste pal\u00e1cio \u00e9 como andar por entre os corredores do passado, este lugar \u00e9 pura hist\u00f3ria al\u00e9m de ser <strong>incrivelmente bonito<\/strong>!<\/p>\n<p>Os hor\u00e1rios de inverno (outubro a mar\u00e7o): todos os dias das 10 at\u00e9 as 18h<\/p>\n<p>No ver\u00e3o (abril a setembro): todos os dias das 10h at\u00e9 as 20h<\/p>\n<p>E tamb\u00e9m de segunda a quinta-feira das 16h at\u00e9 as 18h no inverno e das 18h at\u00e9 as 20h no ver\u00e3o a entrada \u00e9 gratuita para cidad\u00e3os ou pessoas com visto de trabalho ou resid\u00eancia com documentos da Uni\u00e3o Europeia ou iberoamericanos.<\/p>\n<h3>4. Ver o p\u00f4r do sol no Templo de Debod<\/h3>\n<p>Nada melhor que depois de um dia de caminhada ver o <strong>p\u00f4r do sol<\/strong> num dos melhores lugares da cidade. Se deres sorte poder\u00e1s encontrar algum m\u00fasico a tocar ao vivo ou uma apresenta\u00e7\u00e3o de algum artista de rua.<\/p>\n<figure id=\"attachment_16582\" aria-describedby=\"caption-attachment-16582\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-16582 size-medium\" src=\"\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/@simone.maserati-300x250.jpg\" alt=\"que conhecer em amdrid\" width=\"300\" height=\"250\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/@simone.maserati-300x250.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/@simone.maserati.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-16582\" class=\"wp-caption-text\">Photo by @simone.maserati on Instagram<\/figcaption><\/figure>\n<h3>5. Fazer uma caminhada ou um pic nic no Parque do Retiro<\/h3>\n<p>Carinhosamente chamado de <strong>&#8216;Retiro&#8217;<\/strong> pelos madrilenhos, este \u00e9 um dos melhores lugares de Madrid. \u00c9 um parque que une natureza, museus e espa\u00e7os dedicados para as crian\u00e7as. Um passeio ou um pic nic por aqui \u00e9 algo que n\u00e3o poder\u00e1s perder!<\/p>\n<h3>6. Conhecer o Bairro de Lavapi\u00e9s<\/h3>\n<p>Conhecido como o bairro mais <strong>multicultural<\/strong> de Madrid, por ali \u00e9 poss\u00edvel ver lojas e restaurantes de diferentes pa\u00edses do mundo. Sem d\u00favida \u00e9 um dos locais imperd\u00edveis para se perder por entre suas ruas e esquinas.<\/p>\n<h3>7. Ir na &#8216;Plaza Mayor&#8217;<\/h3>\n<p>Esta pra\u00e7a \u00e9 um dos lugares mais <strong>simb\u00f3licos<\/strong> da cidade, seus pr\u00e9dios cor vermelho alaranjado encantam quem por aqui passa. Bem perto daqui tamb\u00e9m h\u00e1 o mercado de <em>San Miguel<\/em> onde \u00e9 poss\u00edvel encontrar tapas e comidas t\u00edpicas espanholas.<\/p>\n<h3>8. Passear por uma das principais avenidades de Madrid: a &#8216;Gran V\u00eda&#8217;<\/h3>\n<p>A Gran V\u00eda \u00e9 uma das avenidas mais <strong>emblem\u00e1ticas<\/strong> da cidade, suas lojas, caf\u00e9s, carros e luzes s\u00e3o o que trazem vida por aqui. A \u00fanica coisa que aconselhamos \u00e9 evitar os hor\u00e1rios de grande movimento como as 9h da manh\u00e3 e as 18h da tarde para que o teu passeio possa ser o mais proveitoso poss\u00edvel.<\/p>\n<figure id=\"attachment_16586\" aria-describedby=\"caption-attachment-16586\" style=\"width: 243px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-16586 size-medium\" src=\"\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/madrid_best_photos-243x300.jpg\" alt=\"fim de semana em madrid\" width=\"243\" height=\"300\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/madrid_best_photos-243x300.jpg 243w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/02\/madrid_best_photos.jpg 750w\" sizes=\"(max-width: 243px) 100vw, 243px\" \/><figcaption id=\"caption-attachment-16586\" class=\"wp-caption-text\">Photo by @madrid_best_photos on Instagram<\/figcaption><\/figure>\n<h3>9. &#8216;El Rastro&#8217; &#8211; o mercado ao ar livre<\/h3>\n<p>Se tua viagem coincidir com um<strong> domingo<\/strong> uma ida ao Rastro \u00e9 <strong>indispens\u00e1vel.<\/strong> Este mercado ao ar livre tem mais de <strong>400 anos<\/strong> de hist\u00f3ria e \u00e9 um dos lugares mais emblem\u00e1ticos da cidade. Aqui \u00e9 poss\u00edvel encontrar de tudo desde roupas e m\u00f3veis at\u00e9 objetos decorativos.<\/p>\n<h3>10. As vistas de Madrid desde o C\u00edrculo de Bellas Artes<\/h3>\n<p>Este \u00e9 um lugar <strong>perfeito<\/strong> para terminar um dia de passeio, daqui \u00e9 poss\u00edvel ver os <strong>principais pontos tur\u00edsticos<\/strong> de Madrid nas alturas. Esta vista panor\u00e2mica \u00e9 <strong>inesquec\u00edvel<\/strong>!<\/p>\n<h3>11. Come\u00e7ar a noite no bairro mais bohemio da cidade: Malasa\u00f1a<\/h3>\n<p>Pelas ruas deste bairro \u00e9 poss\u00edvel encontrar <strong>bares, <\/strong>lugares para comer <strong>tapas<\/strong>, <strong>restaurantes t\u00edpicos,<\/strong>\u00a0de <strong>comida vegana<\/strong> ou apenas de <strong>doces<\/strong>. Por aqui h\u00e1 um pouco de tudo&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left;\">Se ainda tens d\u00favias n\u00f3s te contaremos o <a href=\"\/\/waynabox.com\/pt-pt\/2019\/02\/27\/porque-e-tao-bom-viajar-para-um-destino-surpresa\/\"><strong>porqu\u00ea \u00e9 t\u00e3o bom viajar para um destino surpresa<\/strong><\/a> e como funcionam as escapadinhas da Wayanbox!<\/p>\n<p style=\"text-align: left;\">E agora, j\u00e1 est\u00e1s preparado para esta <strong>aventura<\/strong>?!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid com voos e hotel inclusos. N\u00e3o percas mais tempo e faz uma escapadinha romantica para Madrid por 3 dias. Reserva a tua viagem surpresa e descobre o mundo<\/p>\n","protected":false},"author":21,"featured_media":85682,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"S\u00edtios imperd\u00edveis para conheceres em Madrid - Waynablog","_seopress_titles_desc":"Madrid com voos e hotel inclusos. N\u00e3o percas mais tempo e faz uma escapadinha romantica para Madrid por 3 dias. Reserva a tua viagem surpresa e descobre o mundo","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[1274],"tags":[1226],"class_list":["post-16545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guias-de-viagem","tag-viagem-madrid"],"_links":{"self":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/16545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/comments?post=16545"}],"version-history":[{"count":21,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/16545\/revisions"}],"predecessor-version":[{"id":86554,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/16545\/revisions\/86554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media\/85682"}],"wp:attachment":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media?parent=16545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/categories?post=16545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/tags?post=16545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}