{"id":86722,"date":"2019-12-04T10:07:09","date_gmt":"2019-12-04T09:07:09","guid":{"rendered":"http:\/\/waynabox.com\/?p=86722"},"modified":"2019-12-04T10:12:45","modified_gmt":"2019-12-04T09:12:45","slug":"o-que-visitar-em-granada-em-2-dias","status":"publish","type":"post","link":"https:\/\/waynabox.com\/blog\/pt-pt\/2019\/12\/04\/o-que-visitar-em-granada-em-2-dias\/","title":{"rendered":"O que visitar em Granada em 2 dias"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Se o teu destino fosse Granada saber\u00edas o que fazer por l\u00e1? O que visitar? Onde comer?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se a tua resposta foi n\u00e3o, n\u00f3s temos uma not\u00edcia excelente para comunicar-te: <strong>dicas da Waynabox para uma viagem inesquec\u00edvel<\/strong> numa das cidades mais famosas da Espanha!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Uma viagem de<strong> 2 dias<\/strong> por aqui \u00e9 suficiente para visitares os principais pontos tur\u00edsticos, por isso temos algumas <a href=\"\/\/waynabox.com\/pt-pt\/2019\/06\/04\/tips-para-aproveitares-ao-maximo-o-espaco-da-tua-mala\/\">dicas de como preparar uma mala<\/a> com o essencial e sem ter de pagar adicionais por uma bagagem extra.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Onde ir em Granada<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">A primeira coisa a se fazer quando souberes que o teu destino \u00e9 Granada, \u00e9 reservares as entradas da Alhambra. O ingresso pode ser adquirido online e com diferentes hor\u00e1rios, o recomendado \u00e9 deixares ao menos 3 horas separadas para esta visita.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Depois que o conselho n\u00famero um foi dado, podemos come\u00e7ar a nossa lista de s\u00edtios imperd\u00edveis numa das cidades mais famosas da Espanha. Come\u00e7ar a explorar esta cidade \u00e9 maneira mais f\u00e1cil de perceber um pouco de tudo o que aconteceu por aqui, desde a Conquista \u00c1rabe at\u00e9 a Reconquista crist\u00e3 e os anos posteriores.\u00a0<\/span><\/p>\n<p>Antes de come\u00e7ares a tua viagem, n\u00e3o deixes de ler os nossos conselhos de como <a href=\"\/\/waynabox.com\/pt-pt\/2017\/05\/25\/6-conselhos-viajar-um-preco-baixo-neste-verao-e-ate-conseguir-poupar\/\">viajar por um pre\u00e7o baixo e at\u00e9 poupar<\/a> na tua pr\u00f3xima escapadinha de f\u00e9rias. Assim conseguir\u00e1s aproveitar ao m\u00e1ximo da tua experi\u00eancia connosco.<\/p>\n<h3><span style=\"font-weight: 400;\">1. Alhambra<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">\u00c9 claro que esta lista tem que come\u00e7ar com o s\u00edmbolo da cidade: <strong>Alhambra<\/strong>. Este monumento declarado <strong>Patrim\u00f3nio Mundial da UNESCO<\/strong> foi constru\u00eddo no s\u00e9culo XIII pelos governantes da \u00e9poca. O s\u00edtio possui 140 mil metros quadrados e est\u00e1 dividido em 3 partes:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os Pal\u00e1cios Nasridas, o Generalife e Alcazaba.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">2. O bairro de Albaicin<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Este bairro conhecido pela sua arquitetura \u00e1rabe \u00e9 uma verdadeira j\u00f3ia da cidade. A Carrera del Darro \u00e9 considerada uma das ruas mais bonitas do mundo, as ruas, as lojas e as teter\u00edas (casas de ch\u00e1) te v\u00e3o deixar encantado(a). Al\u00e9m disso, por aqui tu encontrar\u00e1s o <strong>Mirador San Nicolau<\/strong> com uma vista incr\u00edvel da Alhambra, um p\u00f4r do sol por aqui \u00e9 uma das coisas mais bonitas que vais ver na vida.<\/span><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-86733 aligncenter\" src=\"\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/Melhor-roteiro-Granada-300x200.jpg\" alt=\"Melhores miradores de Granada\" width=\"300\" height=\"200\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/Melhor-roteiro-Granada-300x200.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/Melhor-roteiro-Granada-1030x687.jpg 1030w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/Melhor-roteiro-Granada-768x512.jpg 768w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/Melhor-roteiro-Granada-1536x1024.jpg 1536w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/Melhor-roteiro-Granada-2048x1365.jpg 2048w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/Melhor-roteiro-Granada-1024x685.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Aqui tu poder\u00e1s conhecer tamb\u00e9m os banhos ar\u00e1bes constru\u00eddo no s\u00e9culo XI com a finalidade de as pessoas banharem-se nele. Havia tr\u00eas salas: a fria, a t\u00e9pida e a quente. Outros s\u00edtios localizados neste bairro s\u00e3o o Pal\u00e1cio Dar-al-Horra e a Casa Horno de Oro.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">3. O bairro de Sacramonte<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Este bairro \u00e9 mesmo bonito, suas casas brancas com pinturas azuis e as suas vistas s\u00e3o mesmo diferentes de qualquer coisa que j\u00e1 viste. Nessas ruas tu encontrar\u00e1s alguns miradores escondidos e com vistas preciosas.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">4. Catedral<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Esta Catedral foi constru\u00edda pelos reis cat\u00f3licos durante o s\u00e9culo XVI e possui um estilo arquitet\u00f3nico composto por influ\u00eancias renascentistas, barrocas e g\u00f3ticas. A visita inclui a Cripta, os t\u00famulos de alguns reis cat\u00f3licos e um museu.<\/span><\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-86729 aligncenter\" src=\"\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/o-que-visitar-em-Granada-300x200.jpg\" alt=\"O que ver em 2 dias em Granada\" width=\"300\" height=\"200\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/o-que-visitar-em-Granada-300x200.jpg 300w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2019\/12\/o-que-visitar-em-Granada.jpg 700w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3><span style=\"font-weight: 400;\">5. Tapas<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Outra dica imperd\u00edvel \u00e9<strong> comer tapas<\/strong>! E o que exatamente s\u00e3o tapas? S\u00e3o pequenas por\u00e7\u00f5es de comida oferecidas junto com a bebida que pediste, ou seja, tu pedes uma bebida e o bar ou restaurante oferece-te uma tapa. Sim, \u00e9 uma ideia mesmo fixe!\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Alguns s\u00edtios de tapa que s\u00e3o conhecidos como os melhores da cidade s\u00e3o:<\/span><\/p>\n<h4><span style=\"font-weight: 400;\">Diamante (Calle Navas,26)<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Bodegas Casta\u00f1eda (Calle Almireceros esquina com Calle Elvira)<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Casa Julio (Calle Hermosa 5)<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Bar \u00c1vila (calle de Ver\u00f3nica de la Virgen, 16)<\/span><\/h4>\n<h4><span style=\"font-weight: 400;\">Riviera (Calle Cetti Meriem, 7)<\/span><\/h4>\n<h3><span style=\"font-weight: 400;\">6. Flamenco<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Uma das coisas que deves fazer por aqui \u00e9 assistir a um <strong>espet\u00e1culo de flamenco<\/strong> ao vivo, esta que \u00e9 uma dan\u00e7a t\u00edpica da regi\u00e3o al\u00e9m de ser conhecida tamb\u00e9m como um dos s\u00edmbolos da cultura espanhola em todo o mundo. O s\u00edtio mais famoso e tradicional para ires chama-se\u00a0 Zambra, n\u00e3o percas esta oportunidade!<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Granada \u00e9 realmente uma cidade incr\u00edvel e por ser pequena \u00e9 f\u00e1cil ir a p\u00e9 a todos os s\u00edtios e n\u00e3o h\u00e1 porque preocupar-te com transportes e hor\u00e1rios. Os bairros de Albaicin e Sacramonte est\u00e3o cheios de surpresas, por isso o melhor \u00e9 ires caminhando sem pressa e observando cada detalhe. Se queres fazer uma <a href=\"\/\/waynabox.com\/pt\/viagem-surpresa-espanha\">viagem especial a Espanha<\/a> confira aqui os melhores e mais completos pacotes de viagem.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O melhor roteiro do que fazer em Granada. Uma escapadinha de fim de semana inesquec\u00edvel para uma das cidades mais famosas da Espanha<\/p>\n","protected":false},"author":21,"featured_media":86737,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"O que visitar em Granada em 2 dias - Waynablog","_seopress_titles_desc":"O melhor roteiro do que fazer em Granada. Uma escapadinha de fim de semana inesquec\u00edvel para uma das cidades mais famosas da Espanha","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[1274],"tags":[1454],"class_list":["post-86722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guias-de-viagem","tag-granada"],"_links":{"self":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/86722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/comments?post=86722"}],"version-history":[{"count":3,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/86722\/revisions"}],"predecessor-version":[{"id":86744,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/86722\/revisions\/86744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media\/86737"}],"wp:attachment":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media?parent=86722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/categories?post=86722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/tags?post=86722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}