{"id":87546,"date":"2020-02-13T09:37:44","date_gmt":"2020-02-13T08:37:44","guid":{"rendered":"http:\/\/waynabox.com\/?p=87546"},"modified":"2020-02-13T09:38:31","modified_gmt":"2020-02-13T08:38:31","slug":"marta-mendes-viajar-e-quase-como-a-minha-terapia","status":"publish","type":"post","link":"https:\/\/waynabox.com\/blog\/pt-pt\/2020\/02\/13\/marta-mendes-viajar-e-quase-como-a-minha-terapia\/","title":{"rendered":"Marta Mendes: &#8220;Viajar \u00e9 quase como a minha terapia&#8221;"},"content":{"rendered":"<div>\n<p>J\u00e1 conheces o Instagram desta influencer que visitou 23 pa\u00edses? O nome dela \u00e9 Marta Mendes e o suas fotos s\u00e3o capazes de despertar o esp\u00edrito viajante, aventureiro e <em>wanderlust<\/em>\u00a0 de qualquer pessoa!<\/p>\n<p>Confira aqui a nossa entrevista especial e n\u00e3o percas as nossas pr\u00f3ximas novidades deste m\u00eas.<\/p>\n<h3><b>Conta-nos um pouco sobre quando come\u00e7aste a registar as tuas aventuras e viagens no Instagram.<\/b><\/h3>\n<\/div>\n<div>\n<p>Desde sempre que adoro registrar todos os momentos de cada viagem. Para mim, o registo e a produ\u00e7\u00e3o de conte\u00fados dos s\u00edtios que visito permite-me reviver todos os momentos, como se estivesse a viajar de novo para aquele destino.\u200b<\/p>\n<\/div>\n<div>\n<p>Fa\u00e7o sempre muita pesquisa antes de viajar e o Instagram \u00e9 uma \u00f3tima plataforma para descobrir bons roteiros, novos lugares e procurar inspira\u00e7\u00e3o para uma pr\u00f3xima viagem. Al\u00e9m disso, gosto da sensa\u00e7\u00e3o de observar o mundo atrav\u00e9s da lente de quem por ele viaja. \u200b<\/p>\n<\/div>\n<div>\n<p>J\u00e1 me inspirei tantas vezes nas dicas de outros viajantes, que sempre pensei nesta possibilidade de poder partilhar as minhas experi\u00eancias e as minhas aventuras com os outros. Ser capaz de criar conte\u00fados com a qualidade de transportar pessoas a conhecer lugares incr\u00edveis sem sair de casa e inspirar milhares de pessoas ao redor do mundo a viajar e a viver experi\u00eancias transformadoras \u00e9 muito gratificante!<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-87623 aligncenter\" src=\"\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/travel-influencer-240x300.jpeg\" alt=\"Marta Mendes influencer de viagem\" width=\"240\" height=\"300\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/travel-influencer-240x300.jpeg 240w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/travel-influencer-564x705.jpeg 564w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/travel-influencer-450x563.jpeg 450w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/travel-influencer.jpeg 700w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/p>\n<\/div>\n<div>\n<h3><b>Qual foi a tua primeira viagem para fora do pa\u00eds?\u00a0\u00a0<\/b><\/h3>\n<\/div>\n<div>A minha primeira viagem foi um fim de semana prolongado, com a fam\u00edlia, em Paris e na Disneyland. Lembro-me como se fosse ontem. Tinha \u00a010 \/ 11 anos e a emo\u00e7\u00e3o era tanta que nos dias anteriores nem consegui dormir com tanta alegria. Acho que foi logo nessa altura que nasceu o meu &#8220;bichinho pelas viagens&#8221;.<\/div>\n<div>\n<h3><b>Qual foi a coisa mais engra\u00e7ada que j\u00e1 te aconteceu durante uma viagem?<\/b><\/h3>\n<\/div>\n<div>\n<p>A primeira hist\u00f3ria que me ocorre e que no momento nem foi \u201cengra\u00e7ada\u201d, mas sim mais desesperante aconteceu em Marrocos! Atravess\u00e1vamos o deserto e o condutor do jipe que nos transportava tinha tend\u00eancia para acelerar. De repente&#8230; O jipe p\u00e1ra! Quanto mais o condutor acelerava mais as rodas ficavam enterradas na areia. Por momentos, temi o pior&#8230; Est\u00e1vamos no meio do deserto, onde n\u00e3o se avistava rigorosamente nada nem ningu\u00e9m! Sem rede! Com uma temperatura a rondar os 40 graus! Como \u00e9 que \u00edamos sair dali?\u200b O condutor limitava-se a comentar: \u201cn\u00e3o se preocupem, vai aparecer algu\u00e9m!\u201d \u201caparece sempre algu\u00e9m!\u201d. Ao fim de algum tempo apareceu de facto algu\u00e9m, \u2026 Bem l\u00e1 no horizonte\u2026. e caso n\u00e3o tiv\u00e9ssemos corrido, gritado, gesticulado na sua dire\u00e7\u00e3o, acho que ainda estar\u00edamos por l\u00e1. Tal como referi atr\u00e1s, no momento foi desesperante, mas hoje em dia quando conto esta hist\u00f3ria, acabo por me rir imenso da situa\u00e7\u00e3o.<\/p>\n<\/div>\n<div>\n<p>Tamb\u00e9m j\u00e1 tive algumas perip\u00e9cias engra\u00e7adas devido \u00e0 barreira lingu\u00edstica, mas com alguma calma, corre sempre tudo bem.\u200b<\/p>\n<\/div>\n<div>\n<h3><b>Qual o teu destino favorito da Europa? E entre todos os que j\u00e1 visitaste?\u200b<\/b><\/h3>\n<\/div>\n<div>\n<p>Todas as viagens que fiz marcaram-me imenso e de formas completamente diferentes. Todos os destinos t\u00eam o seu pr\u00f3prio encanto. No entanto, posso destacar algumas cidades como: \u200bViena (sem d\u00favida, a cidade europeia mais bonita que j\u00e1 visitei), Paris e Londres. A n\u00edvel de beleza natural, a Cro\u00e1cia e a Eslov\u00e9nia foram, at\u00e9 agora, dos meus destinos europeus favoritos.<\/p>\n<\/div>\n<div>\n<p>Fora da Europa, Nova Iorque \u00e9 uma cidade que vai sempre ser muito especial para mim, tem uma vibe inexplic\u00e1vel; adorei toda a experi\u00eancia que tive em Marrocos, desde a cultura, a gastronomia, o passeio pelo deserto, \u2026; e a \u00cdndia que, era um sonho meu de h\u00e1 muito tempo, surgiu no ano passado e deixou-me completamente rendida. \u200b<\/p>\n<\/div>\n<div>\n<h3><b>J\u00e1 tens a tua pr\u00f3xima viagem planeada?\u200b<\/b><\/h3>\n<\/div>\n<div>\n<p>Sim! Para este ano, j\u00e1 tenho alguns destinos planeados. Algumas escapadinhas de fim de semana e duas viagens de longo curso. Uma delas, tenho a certeza, que vai ser umas das grandes viagens da minha vida! N\u00e3o gosto muito de partilhar estas coisas antes do momento certo, por isso, s\u00f3 vos posso dizer para ficarem atentos \u00e0 minha p\u00e1gina no Instagram!<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-87638 aligncenter\" src=\"\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/Marta-Mendes-entrevista-influencer-257x300.jpeg\" alt=\"Travel influencer waynablog\" width=\"257\" height=\"300\" srcset=\"https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/Marta-Mendes-entrevista-influencer-257x300.jpeg 257w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/Marta-Mendes-entrevista-influencer-605x705.jpeg 605w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/Marta-Mendes-entrevista-influencer-450x525.jpeg 450w, https:\/\/waynabox.com\/blog\/wp-content\/uploads\/2020\/02\/Marta-Mendes-entrevista-influencer.jpeg 700w\" sizes=\"(max-width: 257px) 100vw, 257px\" \/><\/p>\n<\/div>\n<div>\n<h3><b>Tens alguma meta de pa\u00edses para conhecer neste ano?\u200b<\/b><\/h3>\n<\/div>\n<div>\n<p>Nem por isso. Sempre que posso e tenho oportunidade, gosto de viajar. Em 2019, por exemplo, visitei 6 pa\u00edses. Trabalho na \u00e1rea de comunica\u00e7\u00e3o e imagem a full time, portanto tenho sempre de arranjar maneira de conciliar as duas coisas da melhor forma poss\u00edvel. Por vezes, dou por mim a aproveitar todos os meus dias de f\u00e9rias para viajar e depois chego ao final do ano e sinto que n\u00e3o descansei nada. Mas viajar \u00e9 quase como a minha terapia, \u00e9 o que me ajuda a voltar \u00e0 rotina,\u00a0renovada, com mais for\u00e7a e mais vontade de trabalhar e tra\u00e7ar objetivos\u00a0para a minha pr\u00f3xima viagem.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Se depois de leres tudo isso ficaste com vontade de viajar, aproveita para entrar em nosso site e conhecer um pouco mais sobre as nossas <a href=\"\/\/waynabox.com\/pt\">escapadinhas surpresa<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na entrevista especial de hoja a influencer de viagens, Marta Mendes, conta-nos um pouco sobre a sua paix\u00e3o por viajar e conhecer s\u00edtios novos.<\/p>\n","protected":false},"author":21,"featured_media":87631,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"Entrevista com Marta Mendes: &quot;Viajar \u00e9 quase como a minha terapia&quot;","_seopress_titles_desc":"Na entrevista especial de hoja a influencer de viagens, Marta Mendes, conta-nos um pouco sobre a sua paix\u00e3o por viajar e conhecer s\u00edtios novos.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[15],"tags":[],"class_list":["post-87546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-waynabox-pt"],"_links":{"self":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/87546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/comments?post=87546"}],"version-history":[{"count":6,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/87546\/revisions"}],"predecessor-version":[{"id":87643,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/posts\/87546\/revisions\/87643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media\/87631"}],"wp:attachment":[{"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/media?parent=87546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/categories?post=87546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/waynabox.com\/blog\/pt-pt\/wp-json\/wp\/v2\/tags?post=87546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}